{"id":278,"date":"2023-10-09T15:27:57","date_gmt":"2023-10-09T15:27:57","guid":{"rendered":"https:\/\/italiancolor.it\/?page_id=278"},"modified":"2024-05-07T08:32:45","modified_gmt":"2024-05-07T08:32:45","slug":"l-azienda","status":"publish","type":"page","link":"https:\/\/italiancolor.it\/ro\/l-azienda\/","title":{"rendered":"L&#8217; Azienda"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"278\" class=\"elementor elementor-278\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a397e54 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a397e54\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ee9efad\" data-id=\"6ee9efad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4dabb13b elementor-widget elementor-widget-heading\" data-id=\"4dabb13b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Compania<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30fc958b elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30fc958b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22a835bf\" data-id=\"22a835bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5629728a elementor-widget elementor-widget-text-editor\" data-id=\"5629728a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">La ITALIANCOLOR SRL\u00a0\u00e8 una societ\u00e0 totalmente italiana, appartenente a un gruppo con esperienza pluridecennale nella produzione e commercializzazione di prodotti chimici per svariati settori.<\/p><p style=\"text-align: left;\">Nello stabilimento di Bari sono riunite competenze e capacit\u00e0 produttive del pi\u00f9 alto livello, in grado di soddisfare le esigenze di tutti gli operatori del settore. La nostra flessibilit\u00e0 e vicinanza alle condizioni del mercato ci spingono a realizzare progetti di gamme di prodotti personalizzate. Siamo in grado di accedere alle pi\u00f9 performanti specialit\u00e0 chimiche e a garantire disponibilit\u00e0 e puntualit\u00e0 di fornitura.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cf120d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cf120d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-51984d86\" data-id=\"51984d86\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83ac3d2 elementor-widget elementor-widget-image\" data-id=\"83ac3d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"804\" height=\"732\" src=\"https:\/\/italiancolor.it\/wp-content\/uploads\/2023\/10\/image9767-e1696865994529.png\" class=\"attachment-full size-full wp-image-44\" alt=\"\" srcset=\"https:\/\/italiancolor.it\/wp-content\/uploads\/2023\/10\/image9767-e1696865994529.png 804w, https:\/\/italiancolor.it\/wp-content\/uploads\/2023\/10\/image9767-e1696865994529-600x546.png 600w, https:\/\/italiancolor.it\/wp-content\/uploads\/2023\/10\/image9767-e1696865994529-300x273.png 300w, https:\/\/italiancolor.it\/wp-content\/uploads\/2023\/10\/image9767-e1696865994529-768x699.png 768w\" sizes=\"(max-width: 804px) 100vw, 804px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-41aceef7\" data-id=\"41aceef7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d177e60 elementor-widget elementor-widget-spacer\" data-id=\"d177e60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a22ee94 elementor-widget elementor-widget-text-editor\" data-id=\"a22ee94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019azienda si estende su un\u2019area di mq 22.000, di cui 9.000 coperti ed \u00e8 ubicata nella zona industriale di Bari. Al fine di garantire la qualit\u00e0 del prodotto e lo sviluppo di prodotti innovativi, la ITALIANCOLOR SRL, ha acquisito alcune delle figure professionali pi\u00f9 rappresentative della ex Cp Italia.<br \/>La <em>mission<\/em> della Societ\u00e0 consiste non solo nel dare continuit\u00e0 alla produzione di Smalti, Pitture e Vernici con brand Cp Italia ma anche di sviluppare nuovi prodotti speciali e innovativi nel settore dell\u2019edilizia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f9d2fc elementor-widget elementor-widget-text-editor\" data-id=\"7f9d2fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La ITALIANCOLOR SRL produce anche per c\/terzi e a marchio di clienti\/partners pi\u00f9 rappresentativi in Italia e all\u2019Estero.<br \/>Il programma di produzione \u00e8 completo ed innovativo in grado di soddisfare tutte le esigenze del mercato. Professionalit\u00e0 ed esperienza di chimici e tecnici altamente specializzati consentono di ottenere vernicianti con standard qualitativi elevati.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ecad15 elementor-widget elementor-widget-text-editor\" data-id=\"1ecad15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019innovazione non \u00e8 legata alle dimensioni o all\u2019et\u00e0 dell\u2019azienda ma ad un\u2019attivit\u00e0 volta sempre alla ricerca\u2026 ITALIANCOLOR,\u00a0 Maestri del Colore!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c4b8244 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c4b8244\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6c4ba02\" data-id=\"6c4ba02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8484387 elementor-widget elementor-widget-heading\" data-id=\"8484387\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qualit\u00e0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca15717 elementor-widget elementor-widget-text-editor\" data-id=\"ca15717\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tutto il materiale pervenuto in azienda, materia prima o imballo, viene sottoposto a due tipi di controlli:<\/p><ol><li><strong>Amministrativo<\/strong>: si verifica la conformit\u00e0 tra quanto ricevuto e quanto ordinato in termini di colli, quantit\u00e0 e tipo di confezioni.<\/li><li><strong>Tecnico<\/strong>:si effettua un\u2019analisi chimica sulle materie prime per verificare la conformit\u00e0 dei parametri chimico-fisici ai nostri standard qualitativi, e un\u2019analisi funzionale sugli imballi, per verificarne l\u2019integrit\u00e0 e la rispondenza, per alcune serie, alle normative ADR<br \/><br \/><\/li><\/ol><p>Verificata la totale conformit\u00e0, il materiale approvvigionato opportunamente identificato, viene stoccato in apposite aree in attesa di essere immesso nel ciclo produttivo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b42ed87\" data-id=\"b42ed87\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50ddee0 elementor-widget elementor-widget-image\" data-id=\"50ddee0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"200\" height=\"255\" src=\"https:\/\/italiancolor.it\/wp-content\/uploads\/2023\/10\/qua.jpg\" class=\"attachment-large size-large wp-image-290\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b04074 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b04074\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33c7de8\" data-id=\"33c7de8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9c75eb elementor-widget elementor-widget-text-editor\" data-id=\"d9c75eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La produzione viene impostata sulla base di un \u201crapporto di produzione\u201dche indica gli ingredienti necessari alla realizzazione delle diverse tipologie di verniciante, le modalit\u00e0 di lavorazione e l\u2019impianto da utilizzare. A seconda del tipo di produzione, si eseguono controlli di processo: stato di dispersione, finezza di macinazione, temperatura ecc.<br \/>Al termine della lavorazione, ne viene prelevato un campione al fine di effettuare in laboratorio tutti i test qualitativi inerenti al prodotto: viscosit\u00e0, peso specifico, copertura, essiccazione, dilatazione, pennellabilit\u00e0, messa in tinta, gloss, durezza del film, potere di adesione al supporto. Solo se superate tali verifiche, il prodotto viene confezionato.<br \/>Ogni lotto viene identificato in maniera univoca mediante un numero di partita, riportato sul rapporto di produzione, che viene apposto con etichette sui contenitori in fase di confezionamento. Ne viene prelevato un campione, opportunamente identificato, che viene conservato per tre anni a cura del Laboratorio. In caso di segnalazione di anomalia sul prodotto da parte del cliente, \u00e8 possibile risalire, tramite il numero di partita, al prodotto stesso e verificarne le segnalazioni ricevute.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-119017d elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"119017d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-52dcadb\" data-id=\"52dcadb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72280a7 elementor-widget elementor-widget-heading\" data-id=\"72280a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La Logistica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-002b274 elementor-widget elementor-widget-text-editor\" data-id=\"002b274\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Anticipare le esigenze del cliente<\/strong> in termini di gestione del traffico di merce, movimentazione di magazzino, procedure di spedizione al fine di instaurare un vero rapporto di collaborazione con gli operatori della distribuzione<\/p><p><strong>Italiancolor srl <\/strong> ha dotato la propria funzione logistica di programmi informatizzati e attrezzato le aree di imballaggio e spedizione con impianti moderni e automatizzati che garantiscono tempi di confezionamento rapidi e precisi ed estrema flessibilit\u00e0 nella gestione di differenti tipi e dimensioni di imballo.<\/p><p>Ogni impianto \u00e8 dotato di formatore, nastratrice automatica ed etichettatore per la stampa in tempo reale e l&#8217;applicazione automatica dell&#8217;etichetta riportante tutti i dati di riconoscimento del prodotto e codici EAN 13.<br \/>Nella stazione a pallettizzazione, i pallets completi vengono avvolti con film estensibili.<br \/><br \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-54464d0\" data-id=\"54464d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f77b4c5 elementor-widget elementor-widget-image\" data-id=\"f77b4c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"205\" height=\"289\" src=\"https:\/\/italiancolor.it\/wp-content\/uploads\/2023\/10\/logistica01.jpg\" class=\"attachment-large size-large wp-image-294\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f2ab125 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f2ab125\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ba3104\" data-id=\"8ba3104\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-808da3a elementor-widget elementor-widget-text-editor\" data-id=\"808da3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ogni richiesta del cliente \u00e8 gestita secondo le diverse esigenze di tempi e modi ed ogni informazione viene archiviata nella nostre banche dati pertanto \u00e8 possibile conoscere in tempo reale lo stato di evasione dell&#8217;ordine.<br \/>Lo stoccaggio della merce avviene in moderni e capienti magazzini: l&#8217;area di stoccaggio si estende su una superficie totale di oltre 3.500 mq. coperti (permettendo una riserva media di oltre 1.500.000 litri di prodotti vernicianti) consentendo di evadere gli ordini entro 4\/6 giorni lavorativi dalla data di ricevimento.<\/p><p>Per le nostre spedizioni ci avvaliamo dei pi\u00f9 importanti corrieri nazionali ed esteri.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>L&#8217; Azienda La ITALIANCOLOR SRL\u00a0\u00e8 una societ\u00e0 totalmente italiana, appartenente a un gruppo con esperienza pluridecennale nella produzione e commercializzazione di prodotti chimici per svariati settori. Nello stabilimento di Bari sono riunite competenze e capacit\u00e0 produttive del pi\u00f9 alto livello, in grado di soddisfare le esigenze di tutti gli operatori del settore. La nostra flessibilit\u00e0 [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-278","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039; Azienda - Italian Color<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/italiancolor.it\/ro\/l-azienda\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039; Azienda - Italian Color\" \/>\n<meta property=\"og:description\" content=\"L&#8217; Azienda La ITALIANCOLOR SRL\u00a0\u00e8 una societ\u00e0 totalmente italiana, appartenente a un gruppo con esperienza pluridecennale nella produzione e commercializzazione di prodotti chimici per svariati settori. Nello stabilimento di Bari sono riunite competenze e capacit\u00e0 produttive del pi\u00f9 alto livello, in grado di soddisfare le esigenze di tutti gli operatori del settore. La nostra flessibilit\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/italiancolor.it\/ro\/l-azienda\/\" \/>\n<meta property=\"og:site_name\" content=\"Italian Color\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-07T08:32:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/italiancolor.it\/wp-content\/uploads\/2023\/10\/image9767-e1696865994529.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Timp estimat pentru citire\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/italiancolor.it\\\/l-azienda\\\/\",\"url\":\"https:\\\/\\\/italiancolor.it\\\/l-azienda\\\/\",\"name\":\"L' Azienda - Italian Color\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/italiancolor.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/italiancolor.it\\\/l-azienda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/italiancolor.it\\\/l-azienda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/italiancolor.it\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/image9767-e1696865994529.png\",\"datePublished\":\"2023-10-09T15:27:57+00:00\",\"dateModified\":\"2024-05-07T08:32:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/italiancolor.it\\\/l-azienda\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/italiancolor.it\\\/l-azienda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/italiancolor.it\\\/l-azienda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/italiancolor.it\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/image9767-e1696865994529.png\",\"contentUrl\":\"https:\\\/\\\/italiancolor.it\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/image9767-e1696865994529.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/italiancolor.it\\\/l-azienda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/italiancolor.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217; Azienda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/italiancolor.it\\\/#website\",\"url\":\"https:\\\/\\\/italiancolor.it\\\/\",\"name\":\"Italian Color\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/italiancolor.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L' Azienda - Italian Color","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/italiancolor.it\/ro\/l-azienda\/","og_locale":"ro_RO","og_type":"article","og_title":"L' Azienda - Italian Color","og_description":"L&#8217; Azienda La ITALIANCOLOR SRL\u00a0\u00e8 una societ\u00e0 totalmente italiana, appartenente a un gruppo con esperienza pluridecennale nella produzione e commercializzazione di prodotti chimici per svariati settori. Nello stabilimento di Bari sono riunite competenze e capacit\u00e0 produttive del pi\u00f9 alto livello, in grado di soddisfare le esigenze di tutti gli operatori del settore. La nostra flessibilit\u00e0 [&hellip;]","og_url":"https:\/\/italiancolor.it\/ro\/l-azienda\/","og_site_name":"Italian Color","article_modified_time":"2024-05-07T08:32:45+00:00","og_image":[{"url":"https:\/\/italiancolor.it\/wp-content\/uploads\/2023\/10\/image9767-e1696865994529.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Timp estimat pentru citire":"5 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/italiancolor.it\/l-azienda\/","url":"https:\/\/italiancolor.it\/l-azienda\/","name":"L' Azienda - Italian Color","isPartOf":{"@id":"https:\/\/italiancolor.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/italiancolor.it\/l-azienda\/#primaryimage"},"image":{"@id":"https:\/\/italiancolor.it\/l-azienda\/#primaryimage"},"thumbnailUrl":"https:\/\/italiancolor.it\/wp-content\/uploads\/2023\/10\/image9767-e1696865994529.png","datePublished":"2023-10-09T15:27:57+00:00","dateModified":"2024-05-07T08:32:45+00:00","breadcrumb":{"@id":"https:\/\/italiancolor.it\/l-azienda\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/italiancolor.it\/l-azienda\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/italiancolor.it\/l-azienda\/#primaryimage","url":"https:\/\/italiancolor.it\/wp-content\/uploads\/2023\/10\/image9767-e1696865994529.png","contentUrl":"https:\/\/italiancolor.it\/wp-content\/uploads\/2023\/10\/image9767-e1696865994529.png"},{"@type":"BreadcrumbList","@id":"https:\/\/italiancolor.it\/l-azienda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/italiancolor.it\/"},{"@type":"ListItem","position":2,"name":"L&#8217; Azienda"}]},{"@type":"WebSite","@id":"https:\/\/italiancolor.it\/#website","url":"https:\/\/italiancolor.it\/","name":"Italian Color","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/italiancolor.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/italiancolor.it\/ro\/wp-json\/wp\/v2\/pages\/278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/italiancolor.it\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/italiancolor.it\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/italiancolor.it\/ro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/italiancolor.it\/ro\/wp-json\/wp\/v2\/comments?post=278"}],"version-history":[{"count":28,"href":"https:\/\/italiancolor.it\/ro\/wp-json\/wp\/v2\/pages\/278\/revisions"}],"predecessor-version":[{"id":1361,"href":"https:\/\/italiancolor.it\/ro\/wp-json\/wp\/v2\/pages\/278\/revisions\/1361"}],"wp:attachment":[{"href":"https:\/\/italiancolor.it\/ro\/wp-json\/wp\/v2\/media?parent=278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}